{"id":10122,"date":"2023-06-02T17:37:17","date_gmt":"2023-06-02T15:37:17","guid":{"rendered":"https:\/\/www.klima-allianz.ch\/?post_type=beitrag&#038;p=10122"},"modified":"2023-06-06T21:35:36","modified_gmt":"2023-06-06T19:35:36","slug":"stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque","status":"publish","type":"beitrag","link":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/","title":{"rendered":"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat &#8211; double risque"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\"><strong>Dans la pratique bancaire, la protection du climat devient d&rsquo;importance syst\u00e9mique<\/strong><\/span><\/p>\n<p>Avec son casino financier, Credit Suisse s&rsquo;est auto-d\u00e9mont\u00e9e. Son absorption par l&rsquo;UBS a modifi\u00e9 <span style=\"text-decoration: underline;\">n\u00e9gativement<\/span> le <span style=\"text-decoration: underline;\">paysage des risques<\/span> pour la place financi\u00e8re.\u00a0La nouvelle m\u00e9ga-banque est un m\u00e9ga-risque : le syst\u00e8me financier suisse se compose d&rsquo;une grosse masse de risque expos\u00e9e \u00e0 l&rsquo;\u00e9tranger et de nombreux acteurs plus petits, mais qui sont tous ensemble dans le m\u00eame bateau. <span style=\"text-decoration: underline;\">De plus<\/span>, une <span style=\"text-decoration: underline;\">crise financi\u00e8re li\u00e9e au climat<\/span> d&rsquo;une ampleur potentiellement similaire se profile de plus en plus clairement <span style=\"text-decoration: underline;\">\u00e0 l&rsquo;horizon.<\/span> Sans contre-mesures, fond\u00e9es sur le recensement et la mesure d&rsquo;un paysage de risques d\u00e9sormais deux fois plus important,\u00a0<span style=\"text-decoration: underline;\">la Suisse,<\/span> d\u00e9pendante de sa place financi\u00e8re, son \u00e9conomie et sa soci\u00e9t\u00e9 seraient <span style=\"text-decoration: underline;\">expos\u00e9es de mani\u00e8re nettement plus importante<\/span> que d&rsquo;autres pays.<\/p>\n<p><span style=\"text-decoration: underline;\">La protection du climat dans la pratique bancaire est d&rsquo;importance syst\u00e9mique<\/span>. L&rsquo;Alliance climatique pose aux leaders d&rsquo;opinion et aux d\u00e9cideurs politiques et \u00e9conomiques de la place financi\u00e8re suisse une <span style=\"text-decoration: underline;\">s\u00e9rie de questions urgentes<\/span> qui d\u00e9coulent des conclusions internationales &#8211; mais qui sont ignor\u00e9es dans notre pays.<\/p>\n<p><span style=\"text-decoration: underline;\">D\u00e9clin et chute du Credit Suisse : un point de bascule<\/span><\/p>\n<p>La nouvelle UBS donne naissance \u00e0 une m\u00e9gabanque int\u00e9gr\u00e9e au syst\u00e8me mondial, le <a href=\"https:\/\/www.handelszeitung.ch\/banking\/die-neue-ubs-uberragt-in-puncto-grosse-fast-alle-590764#:~:text=Von%20Peter%20Rohner&amp;text=Gemessen%20an%20der%20Bilanzsumme%20per,Billionen%20Franken%20auf%20die%20Waage.\">num\u00e9ro 6<\/a> en Europe. Pour la place financi\u00e8re suisse, il s&rsquo;agit d&rsquo;un g\u00e9ant dont le risque syst\u00e9mique \u00e9clipse les banques d&rsquo;importance syst\u00e9mique restantes &#8211; Z\u00fcrcher Kantonalbank, Raiffeisen, Postfinance.<\/p>\n<p>Les effets n\u00e9fastes d&rsquo;un \u00e9ventuel nouvel effondrement seraient <span style=\"text-decoration: underline;\">concentr\u00e9s<\/span> de mani\u00e8re disproportionn\u00e9e par rapport aux autres pays &#8211; <span style=\"text-decoration: underline;\">sur la place financi\u00e8re, l&rsquo;\u00e9conomie et la population suisses<\/span>. Le monde politique veut s&rsquo;attaquer \u00e0 cette crise existentielle en cr\u00e9ant une commission d&rsquo;enqu\u00eate parlementaire \u00ab<a href=\"https:\/\/www.blick.ch\/fr\/news\/suisse\/apres-la-debacle-le-conseil-federal-est-favorable-a-une-enquete-parlementaire-sur-le-rachat-de-cs-id18631436.html\">CEP Credit Suisse<\/a>\u00bb. Mais une r\u00e9trospective dont le champ de vision se limite aux risques syst\u00e9miques \u00abconventionnels\u00bb connus depuis la crise financi\u00e8re de 2008 sera-t-elle suffisante ?<\/p>\n<p><span style=\"text-decoration: underline;\">Nouvelle crise \u00e0 l&rsquo;horizon : point de bascule climatique<\/span><\/p>\n<p>L&rsquo;image du pr\u00e9sent article, le \u00abGreen Swan\u00bb, est la figure de couverture de l&rsquo;\u00e9tude \u00ab<a href=\"https:\/\/www.bis.org\/publ\/othp31.pdf\">Central Banking and financial stability in the Age of Climate Change<\/a>\u00bb publi\u00e9e en janvier 2020 par la <a href=\"https:\/\/www.bis.org\/topic\/green_finance.htm?m=2704\">Banque des r\u00e8glements internationaux (BRI)<\/a> \u00e0 B\u00e2le, la banque centrale mondiale des banques centrales.<\/p>\n<p>Qu&rsquo;entend la BRI par cygne vert ? Les \u00e9v\u00e9nements perturbateurs qui, selon elle, sont difficilement pr\u00e9visibles et se produisent pourtant soudainement, sont un \u00abBlack Swan\u00bb. La BRI se r\u00e9f\u00e8re \u00e0 un livre bien connu d&rsquo;un \u00e9conomiste financier avec ce titre, qui a \u00e9t\u00e9 publi\u00e9 peu de temps avant le d\u00e9but de la crise financi\u00e8re.<\/p>\n<p>En revanche, le \u00ab<span style=\"text-decoration: underline;\">Green Swan<\/span>\u00bb\u00a0de la BRI, dont l&rsquo;apparition et l&rsquo;effet destructeur sur le syst\u00e8me mondial sont <span style=\"text-decoration: underline;\">pr\u00e9visibles avec certitude<\/span>, est l&rsquo;apparition des cascades de <a href=\"https:\/\/www.polytechnique-insights.com\/en\/columns\/economy\/green-swans-a-tipping-point-for-global-finance\/#note-1\">points de basculement<\/a> pr\u00e9dits depuis longtemps par la science climatique. La BRI les reproduit en d\u00e9tail. Sans contre-mesures prises \u00e0 temps, on passerait en peu de temps d&rsquo;un \u00e9tat physique encore stable au d\u00e9passement des limites plan\u00e9taires, ce qui entra\u00eenerait une succession dense de catastrophes pour l&rsquo;humanit\u00e9 et la plan\u00e8te Terre.<\/p>\n<p>Une telle situation, \u00e0 l&rsquo;instar de la crise Covid, obligerait les \u00c9tats \u00e0 intervenir fortement mais de mani\u00e8re pr\u00e9cipit\u00e9e \u00e0 l&rsquo;\u00e9chelle de la plan\u00e8te, ce qui, comme on peut le craindre, serait en outre mis en \u0153uvre trop tardivement. Au final, il en r\u00e9sulterait non seulement d&rsquo;immenses souffrances pour un grand nombre de personnes et la perte des services essentiels des \u00e9cosyst\u00e8mes et de la biodiversit\u00e9. Ce sont \u00e9galement les secteurs de l&rsquo;\u00e9conomie mondiale qui d\u00e9pendent des \u00e9nergies fossiles qui verront \u00a0leur mod\u00e8le \u00e9conomique s&rsquo;\u00e9vaporer \u00e0 la suite des dispositions brusques prises en faveur de la transition \u00e9nerg\u00e9tique. Les cr\u00e9dits bancaires ne sont pas rembours\u00e9s, les actions et les obligations deviennent des papiers de ferraille, les banques deviennent simultan\u00e9ment illiquides, les syst\u00e8mes financiers s&rsquo;effondrent les uns apr\u00e8s les autres. Les banques qui n&rsquo;ont pas r\u00e9duit \u00e0 temps leur exposition aux risques climatiques sont les premi\u00e8res touch\u00e9es.<\/p>\n<p>L&rsquo;Alliance climatique n&rsquo;a pas invent\u00e9 le sc\u00e9nario pr\u00e9sent\u00e9 : c&rsquo;est la BRI qui d\u00e9crit ainsi son \u00abGreen Swan\u00bb. C&rsquo;est pour elle la figure qui confirme la n\u00e9cessit\u00e9 pour les banques centrales et leurs activit\u00e9s de surveillance d&rsquo;int\u00e9grer les risques syst\u00e9miques li\u00e9s au climat dans la gestion des risques.<\/p>\n<p>La BRI s&rsquo;oppose \u00e0 ce que les banques centrales soient une fois de plus appel\u00e9es \u00e0 la rescousse en tant que \u00abrescuers of last resort\u00bb en cas d&rsquo;urgence du type\u00a0\u00abGreen Swan\u00bb. La politique et l&rsquo;\u00e9conomie sont invit\u00e9es \u00e0 agir selon le principe de pr\u00e9caution, afin de ne pas \u00eatre contraintes d&rsquo;intervenir en tant que pompiers et \u00abclimate rescuers of last resort\u00bb.<\/p>\n<p>En ce qui concerne les banques centrales, elle les appelle \u00e0 adopter une approche proactive, r\u00e9sum\u00e9e sous le slogan \u00abContribute to Coordination to Combat Climate Change\u00bb. Concr\u00e8tement, mieux vaut pr\u00e9venir que gu\u00e9rir. Un message clair que les banques centrales devraient envoyer aux politiques en faveur de lois climatiques dans tous les secteurs de l&rsquo;\u00e9conomie et de la soci\u00e9t\u00e9.<\/p>\n<p>En vertu du principe de pr\u00e9caution, il s&rsquo;agit donc d&rsquo;\u00e9viter que le cygne vert n&rsquo;apparaisse et, s&rsquo;il est tout de m\u00eame pr\u00e9sent en raison d&rsquo;un \u00e9chec des politiques climatiques des \u00c9tats, d&rsquo;en limiter les cons\u00e9quences financi\u00e8res n\u00e9gatives &#8211; dans la mesure o\u00f9 cela est encore possible.<\/p>\n<p><span style=\"text-decoration: underline;\">Double menace pour la stabilit\u00e9 du syst\u00e8me : casino financier plus climat<\/span><\/p>\n<p>Jetons maintenant un regard en arri\u00e8re, apr\u00e8s la crise financi\u00e8re de 2007-2008 : les d\u00e9cideurs en Suisse ont-ils d\u00e9j\u00e0 tir\u00e9 les cons\u00e9quences d\u00e9j\u00e0 simplement dans le domaine classique des risques syst\u00e9miques ? Non. Il y a des ann\u00e9es d\u00e9j\u00e0, des scientifiques financiers clairvoyants sur le plan mondial, comme l&rsquo;\u00e9conomiste de Stanford Anat Admati ou Marc Chesney, directeur de l&rsquo;Institut Banking and Finance de l&rsquo;Universit\u00e9 de Zurich, ont demand\u00e9 des <a href=\"https:\/\/www.core-econ.org\/the-economy\/book\/text\/anat-admati_whats-wrong-with-banking-transcript.html\">r\u00e8gles bancaires beaucoup plus strictes<\/a> pour la gestion de ces risques syst\u00e9miques classiques : \u00ab<a href=\"https:\/\/www.infosperber.ch\/wirtschaft\/kapitalmarkt\/marc-chesney-die-wettgeschaefte-der-grossbanken-verbieten\/\">Ce qui aurait d\u00fb \u00eatre impos\u00e9 et ce qui a \u00e9t\u00e9 n\u00e9glig\u00e9<\/a>\u00bb.<\/p>\n<p>En particulier :<\/p>\n<ul>\n<li>20-30% de fonds propres au lieu de 5% seulement,<\/li>\n<li>s\u00e9paration des banques d&rsquo;importance syst\u00e9mique mondiale et nationale en banques d&rsquo;investissement et banques commerciales,<\/li>\n<li>sym\u00e9trie des bonus avec de nouvelles p\u00e9nalit\u00e9s pour les \u00e9tages de la direction,<\/li>\n<li>surveillance des acrobaties type casino financier qui ont conduit notamment aux scandales <a href=\"https:\/\/www.theguardian.com\/business\/2023\/feb\/28\/credit-suisse-greensill-swiss-bank-finma\">Greensill<\/a> et <a href=\"https:\/\/www.theguardian.com\/business\/2021\/apr\/22\/credit-suisse-records-almost-600m-loss-on-archegos-collapse\">Archegos<\/a>,<\/li>\n<li>certification des produits financiers d\u00e9riv\u00e9s potentiellement toxiques et des constructions financi\u00e8res non transparentes servant \u00e0 la sp\u00e9culation.<\/li>\n<\/ul>\n<p>Si la politique et le secteur financier suisses avaient tir\u00e9 les bonnes conclusions, suivi la m\u00eame ligne de conduite et mis en \u0153uvre des mesures d\u00e9cisives de ce type et de cette rigueur, l&rsquo;effondrement du Credit Suisse aurait pu \u00eatre \u00e9vit\u00e9. Le monde politique n&rsquo;a pas voulu doter les autorit\u00e9s de surveillance, la FINMA et la Banque nationale suisse (BNS), des mandats et des moyens de pouvoir n\u00e9cessaires. Ce manquement a conduit \u00e0 ce que le m\u00eame \u00abBlack Swan\u00bb frappe pour la deuxi\u00e8me fois. Il ne s&rsquo;agit plus d&rsquo;un cygne noir &#8211; ce qui est expos\u00e9, c&rsquo;est le vol \u00e0 l&rsquo;aveuglette auquel les d\u00e9cideurs ont d\u00e9cid\u00e9 de se livrer, en d\u00e9pit des avertissements de la partie pr\u00e9voyante de la science financi\u00e8re.<\/p>\n<p>Mais nous sommes d\u00e9sormais confront\u00e9s \u00e0 une situation doublement nouvelle. Depuis la crise financi\u00e8re, l&rsquo;urgence de prot\u00e9ger le syst\u00e8me s&rsquo;est accrue en raison de la crise climatique de plus en plus visible &#8211; le \u00abGreen Swan\u00bb \u00e0 l&rsquo;horizon.<\/p>\n<p>Nous sommes en pr\u00e9sence de <span style=\"text-decoration: underline;\">deux amas de risques<\/span> : la<span style=\"text-decoration: underline;\"> crise financi\u00e8re classique<\/span> et la <span style=\"text-decoration: underline;\">crise financi\u00e8re climatique<\/span>.<\/p>\n<p>Il faut se pr\u00e9munir contre cette double crise :<\/p>\n<ul>\n<li>enfin emp\u00eacher que le cygne noir, qui n&rsquo;\u00e9tait pas facilement pr\u00e9visible \u00e0 l&rsquo;\u00e9poque, ne se manifeste pour la troisi\u00e8me fois sous la forme d&rsquo;une crise financi\u00e8re classique d\u00e9sastreuse,<\/li>\n<li>et enfin percevoir ce cygne vert, le saisir, l&rsquo;analyser, en tirer les cons\u00e9quences et pr\u00e9venir la crise climatique en tant que d\u00e9sastre physique et financier.<\/li>\n<\/ul>\n<p>Le d\u00e9fi \u00e9conomique pour la place financi\u00e8re suisse est donc double :<\/p>\n<ul>\n<li>La crise financi\u00e8re classique potentielle, qui s&rsquo;est encore intensifi\u00e9e avec la nouvelle m\u00e9ga-UBS en tant que masse \u00abtoo big to fail\u00bb. Elle exige des interventions de stabilisation du syst\u00e8me dans le domaine de la <span style=\"text-decoration: underline;\">gouvernance n\u00e9cessaire pour se pr\u00e9munir contre les aberrations du casino financier.<\/span><\/li>\n<li>La crise climatique qui en d\u00e9coule, due \u00e0 l&rsquo;exposition persistante aux \u00e9nergies fossiles, aux secteurs \u00e9conomiques d\u00e9pendant des \u00e9nergies fossiles et \u00e0 ceux qui sont autrement n\u00e9fastes pour le climat (comme l&rsquo;agriculture non durable, la d\u00e9forestation, la surexploitation de l&rsquo;environnement et la destruction de la biodiversit\u00e9). Elle exige des interventions de stabilisation du syst\u00e8me afin d&rsquo;\u00e9largir la gouvernance \u00e0 la <span style=\"text-decoration: underline;\">dimension de l&rsquo;exposition aux risques fossiles.\u00a0<\/span><\/li>\n<\/ul>\n<p>A cela s&rsquo;ajoute l&rsquo;urgence pour la Suisse de <span style=\"text-decoration: underline;\">responsabiliser sa place financi\u00e8re<\/span> &#8211; en appliquant le principe de pr\u00e9caution &#8211; afin d&rsquo;apporter sa juste contribution pour \u00e9viter la <span style=\"text-decoration: underline;\">crise climatique physique<\/span> avec les catastrophes climatiques qui s&rsquo;accumulent.<\/p>\n<p>Sont imp\u00e9ratifs :<\/p>\n<ul>\n<li>un arr\u00eat d\u00e9termin\u00e9 du financement de l&rsquo;augmentation des \u00e9missions de gaz \u00e0 effet de serre,<\/li>\n<li>la mise en route d&rsquo;un m\u00e9canisme de d\u00e9carbonisation rapide et de r\u00e9orientation verte des flux financiers.<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\">La protection du climat dans la pratique bancaire est d&rsquo;importance syst\u00e9mique &#8211; les questions pressantes de l&rsquo;Alliance climatique<\/span><\/p>\n<p>Pourquoi la politique ne s&rsquo;occupe-t-elle pas, dans le cadre des d\u00e9lib\u00e9rations \u00e0 venir au Parlement, de pr\u00e9parer des d\u00e9cisions qui garantissent la stabilit\u00e9 du syst\u00e8me face \u00e0 ce double risque ?<\/p>\n<p>Concr\u00e8tement, des dispositions sont mises en place pour que &#8230;<\/p>\n<ul>\n<li>&#8230; que la <span style=\"text-decoration: underline;\">Finma<\/span> soit charg\u00e9e de <span style=\"text-decoration: underline;\">pr\u00e9venir \u00e0 la fois les aberrations du casino financier et l&rsquo;exposition aux risques climatiques fossiles<\/span>, en particulier de la nouvelle m\u00e9ga-banque, mais aussi des autres banques et assurances concern\u00e9es de la place financi\u00e8re &#8211; et qu&rsquo;elle soit dot\u00e9e \u00e0 cet effet des des moyens r\u00e9glementaires n\u00e9cessaires pour les faire respecter ?<\/li>\n<\/ul>\n<ul>\n<li>&#8230; le mandat de surveillance <span style=\"text-decoration: underline;\">microprudentielle<\/span> confi\u00e9 \u00e0 la Finma est compl\u00e9t\u00e9 par la <span style=\"text-decoration: underline;\">gestion directe des risques climatique<\/span>s, c&rsquo;est-\u00e0-dire qu&rsquo;elle est charg\u00e9e d&rsquo;imposer \u00e0 la m\u00e9ga-banque UBS ainsi qu&rsquo;\u00e0 d&rsquo;autres gestionnaires de fortune et financiers actifs au niveau mondial &#8211; Banque cantonale de Zurich, Pictet, Julius Baer, Blackrock Suisse, Lombard Odier, Edmond de Rothschild et d&rsquo;autres &#8211; des dispositions qui augmentent les exigences de fonds propres sur leurs bilans dans la mesure des financements \u00e0 risque climatique ? Dans la mise en \u0153uvre, la proposition d&rsquo;une r\u00e8gle \u00ab<a href=\"https:\/\/www.finance-watch.org\/the-one-for-one-rule-a-way-for-cop26-ambitions-to-manifest-in-policy\/\">One-for-One<\/a>\u00bb pourrait servir de base de r\u00e9flexion. Celle-ci propose que pour chaque EUR\/USD avec lequel de nouveaux combustibles fossiles sont financ\u00e9s, les banques et les assurances soient responsables des pertes \u00e9ventuelles \u00e0 hauteur d&rsquo;un EUR\/USD, etc. de leurs fonds propres.<\/li>\n<\/ul>\n<ul>\n<li>&#8230; que le mandat de surveillance <span style=\"text-decoration: underline;\">macroprudentielle<\/span> confi\u00e9 \u00e0 la <span style=\"text-decoration: underline;\">BNS<\/span> soit <span style=\"text-decoration: underline;\">compl\u00e9t\u00e9 par les risques syst\u00e9miques macro\u00e9conomiques li\u00e9s au climat,<\/span> \u00e0 savoir l&rsquo;analyse de ces risques \u00e0 l&rsquo;aide d&rsquo;analyses et de stress tests sp\u00e9cifiques \u00e0 la Suisse et la <span style=\"text-decoration: underline;\">recommandation de mesures r\u00e9glementaires qui en d\u00e9coulent \u00e0 l&rsquo;attention du monde politique et de l&rsquo;\u00e9conomie financi\u00e8re<\/span> &#8211; comme<span style=\"text-decoration: underline;\"> le font d\u00e9j\u00e0 la BRI et le <a href=\"https:\/\/www.ngfs.net\/en\">Network for Greening of the Financial System<\/a><\/span>, un r\u00e9seau mondial de banques centrales en place ? Il est incompr\u00e9hensible que la<span style=\"text-decoration: underline;\"> BNS, banque centrale de l&rsquo;un des pays potentiellement les plus touch\u00e9s<\/span>, ignore la crise syst\u00e9mique \u00e0 venir.<\/li>\n<\/ul>\n<ul>\n<li>&#8230; la\u00a0<span style=\"text-decoration: underline;\">BNS<\/span> re\u00e7oit le mandat de d\u00e9carboniser ses r\u00e9serves mon\u00e9taires sup\u00e9rieures \u00e0 la moyenne de ses <span style=\"text-decoration: underline;\">investissements \u00e0 l&rsquo;\u00e9tranger<\/span>, conform\u00e9ment au principe de pr\u00e9caution de la BRI, la banque centrale des banques centrales qui lui est superpos\u00e9e ? Son alignement sur l&rsquo;objectif net z\u00e9ro au plus tard en 2050 pour atteindre l&rsquo;objectif de 1,5\u00b0C de l&rsquo;Accord de Paris sur le climat est urgent. Aujourd&rsquo;hui, elle n&rsquo;est pas un mod\u00e8le pour les acteurs du march\u00e9 de la place financi\u00e8re suisse. Pour remplir sa mission, elle doit prendre les devants en contribuant elle-m\u00eame au de-risking pour pr\u00e9server la stabilit\u00e9 du syst\u00e8me.<\/li>\n<\/ul>\n<ul>\n<li>&#8230; en exigeant des <span style=\"text-decoration: underline;\">banques<\/span> qu&rsquo;elles mettent leurs <span style=\"text-decoration: underline;\">activit\u00e9s de financement direct et de \u00abUnderwriting\u00bb<\/span> en conformit\u00e9 avec le s<a href=\"https:\/\/iea.blob.core.windows.net\/assets\/deebef5d-0c34-4539-9d0c-10b13d840027\/NetZeroby2050-ARoadmapfortheGlobalEnergySector_CORR.pdf\">c\u00e9nario 1,5\u00b0C de l&rsquo;Agence internationale de l&rsquo;\u00e9nergie (AIE)<\/a> &#8211; <span style=\"text-decoration: underline;\">z\u00e9ro net d&rsquo;ici 2050<\/span> &#8211; par le biais d&rsquo;accords sectoriels et de l&rsquo;examen d&rsquo;engagements volontaires, mais aussi, si n\u00e9cessaire, de r\u00e9glementations ?\u00a0La priorit\u00e9 absolue est le respect du <span style=\"text-decoration: underline;\">constat normatif<\/span> de l&rsquo;AIE : \u00abYear 2021 &#8211; No new unabated coal power plants approved for development ; no new oil and gas fields approved for development ; no new coal mines or mine extensions\u00bb. Ces r\u00e9allocations, qui conduisent \u00e9galement \u00e0 la remont\u00e9e des financements des promoteurs de la transition \u00e9nerg\u00e9tique, r\u00e9duisent l&rsquo;exposition des banques aux risques climatiques.<\/li>\n<\/ul>\n<ul>\n<li>&#8230; en\u00a0exigeant des <span style=\"text-decoration: underline;\">banques<\/span> et des <span style=\"text-decoration: underline;\">assurances<\/span>, par le biais d&rsquo;accords sectoriels et de l&rsquo;examen d&rsquo;engagements volontaires, mais aussi, si n\u00e9cessaire, de r\u00e9glementations, une <span style=\"text-decoration: underline;\">croissance cibl\u00e9e des cr\u00e9dits verts \u00e0 taux r\u00e9duit<\/span> accord\u00e9s aux entreprises nationales (p. ex. aux PME) et des <span style=\"text-decoration: underline;\">hypoth\u00e8ques<\/span> accord\u00e9es aux particuliers en Suisse ? Cette mesure augmente la pression pour que les banques soient proactives dans la transition \u00e9nerg\u00e9tique.<\/li>\n<\/ul>\n<ul>\n<li>&#8230; en exigeant des gestionnaires de fortune (<span style=\"text-decoration: underline;\">Asset Management des banques, assurances et autres institutions financi\u00e8res<\/span>), par le biais d&rsquo;accords sectoriels et de l&rsquo;examen d&rsquo;engagements volontaires, mais aussi, si n\u00e9cessaire, de r\u00e9glementations, qu&rsquo;ils se fixent comme objectif un Paris Alignment conforme \u00e0 1.5\u00b0C avec un z\u00e9ro net au plus tard en 2050 ? A savoir, la r\u00e9duction annuelle des \u00e9missions de gaz \u00e0 effet de serre financ\u00e9e par l&rsquo;ensemble de ses volumes d&rsquo;investissement plac\u00e9s sur le march\u00e9 et g\u00e9r\u00e9s pour le compte d&rsquo;investisseurs priv\u00e9s et institutionnels &#8211; \u00e0 atteindre via 1) un r\u00e9\u00e9quilibrage de l&rsquo;offre de produits financiers sur le march\u00e9 avec la <span style=\"text-decoration: underline;\">promotion de produits durables et Paris-compatibles<\/span>, 2) en int\u00e9grant de <span style=\"text-decoration: underline;\">mani\u00e8re autonome<\/span> une <span style=\"text-decoration: underline;\">trajectoire de d\u00e9carbonisation<\/span>\u00a0des produits <span style=\"text-decoration: underline;\">d\u00e9j\u00e0 sur le march\u00e9<\/span>, 3) en s&rsquo;attaquant \u00e0 la prise d&rsquo;influence actionnariale et en la renfor\u00e7ant (<span style=\"text-decoration: underline;\">Active Ownership<\/span> globale avec un engagement cibl\u00e9 vis-\u00e0-vis des multinationales ayant un fort impact carbone, combin\u00e9 avec un Proxy Voting climatiquement efficace), et 4) en r\u00e9orientant de mani\u00e8re cibl\u00e9e les flux financiers vers les vecteurs de la transition \u00e9nerg\u00e9tique <span style=\"text-decoration: underline;\">(Impact Investing<\/span>). Ce paquet de mesures prot\u00e8ge les <span style=\"text-decoration: underline;\">clients priv\u00e9s et institutionnels<\/span> (notamment aussi les <span style=\"text-decoration: underline;\">caisses de pension<\/span>) contre les cons\u00e9quences d&rsquo;un d\u00e9sastre financier d\u00fb \u00e0 une crise syst\u00e9mique li\u00e9e au climat et contribue en outre de mani\u00e8re d\u00e9terminante \u00e0 la redirection des flux financiers.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Sandro Leuenberger, Place financi\u00e8re et climat, politique, <a href=\"https:\/\/alliance-climatique.ch\/campagnes\/caisses-de-pension\/\">rating caisses de pension<\/a>, <a href=\"mailto:sandro.leuenberger@klima-allianz.ch\">sandro.leuenberger@klima-allianz.ch<\/a>\u00a0(Auteur et contact)<\/p>\n<p>Asti Roesle, Place financi\u00e8re et climat, <a href=\"https:\/\/alliance-climatique.ch\/campagnes\/banque-nationale\/\">Banque nationale<\/a>, <a href=\"mailto:asti.roesle@klima-allianz.ch\">asti.roesle@klima-allianz.ch<\/a> (contact)<\/p>\n","protected":false},"featured_media":10073,"template":"","categories":[17],"class_list":["post-10122","beitrag","type-beitrag","status-publish","has-post-thumbnail","hentry","category-news-fr-2"],"better_featured_image":{"id":10073,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":744,"height":912,"file":"BIS-Green-Swan.png","filesize":493415,"sizes":{"medium":{"file":"BIS-Green-Swan-245x300.png","width":245,"height":300,"mime-type":"image\/png","filesize":60576,"source_url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan-245x300.png"},"thumbnail":{"file":"BIS-Green-Swan-489x600.png","width":489,"height":600,"mime-type":"image\/png","filesize":193949,"source_url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan-489x600.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":10122,"source_url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png"},"acf":{"inhaltstyp_mediabox":"image","galerie":null,"video_html":null,"video_vimeo":"","downloads":[10125,10126,9842],"links":[{"linktitel":"Central Banking and financial stability in the Age of Climate Change, BIS","url":"https:\/\/www.bis.org\/publ\/othp31.pdf"},{"linktitel":"Green swans: a tipping point for global finance, Polytechnique Insights\/BIS","url":"https:\/\/www.polytechnique-insights.com\/en\/columns\/economy\/green-swans-a-tipping-point-for-global-finance\/#note-1"},{"linktitel":"","url":""}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique\" \/>\n<meta property=\"og:description\" content=\"Dans la pratique bancaire, la protection du climat devient d&rsquo;importance syst\u00e9mique Avec son casino financier, Credit Suisse s&rsquo;est auto-d\u00e9mont\u00e9e. Son absorption par l&rsquo;UBS a modifi\u00e9 n\u00e9gativement le paysage des risques pour la place financi\u00e8re.\u00a0La nouvelle m\u00e9ga-banque est un m\u00e9ga-risque : le syst\u00e8me financier suisse se compose d&rsquo;une grosse masse de risque expos\u00e9e \u00e0 l&rsquo;\u00e9tranger et &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/\" \/>\n<meta property=\"og:site_name\" content=\"Alliance Climatique\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T19:35:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/\",\"name\":\"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/BIS-Green-Swan.png\",\"datePublished\":\"2023-06-02T15:37:17+00:00\",\"dateModified\":\"2023-06-06T19:35:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/BIS-Green-Swan.png\",\"contentUrl\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/BIS-Green-Swan.png\",\"width\":744,\"height\":912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beitr\u00e4ge\",\"item\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat &#8211; double risque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\",\"name\":\"Alliance Climatique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#organization\",\"name\":\"Klima-Allianz\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/KA-Favicon-Kreis-1.png\",\"contentUrl\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/KA-Favicon-Kreis-1.png\",\"width\":512,\"height\":512,\"caption\":\"Klima-Allianz\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/","og_locale":"fr_FR","og_type":"article","og_title":"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique","og_description":"Dans la pratique bancaire, la protection du climat devient d&rsquo;importance syst\u00e9mique Avec son casino financier, Credit Suisse s&rsquo;est auto-d\u00e9mont\u00e9e. Son absorption par l&rsquo;UBS a modifi\u00e9 n\u00e9gativement le paysage des risques pour la place financi\u00e8re.\u00a0La nouvelle m\u00e9ga-banque est un m\u00e9ga-risque : le syst\u00e8me financier suisse se compose d&rsquo;une grosse masse de risque expos\u00e9e \u00e0 l&rsquo;\u00e9tranger et &hellip; Continued","og_url":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/","og_site_name":"Alliance Climatique","article_modified_time":"2023-06-06T19:35:36+00:00","og_image":[{"width":744,"height":912,"url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/","url":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/","name":"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat - double risque &#8226; Alliance Climatique","isPartOf":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/#primaryimage"},"image":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/#primaryimage"},"thumbnailUrl":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png","datePublished":"2023-06-02T15:37:17+00:00","dateModified":"2023-06-06T19:35:36+00:00","breadcrumb":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/#primaryimage","url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png","contentUrl":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/BIS-Green-Swan.png","width":744,"height":912},{"@type":"BreadcrumbList","@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/stabilite-de-systeme-apres-le-crash-du-credit-suisse-casino-financier-plus-climat-double-risque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.klima-allianz.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Beitr\u00e4ge","item":"https:\/\/www.klima-allianz.ch\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"Stabilit\u00e9 de syst\u00e8me apr\u00e8s le crash du Cr\u00e9dit Suisse : casino financier plus climat &#8211; double risque"}]},{"@type":"WebSite","@id":"https:\/\/www.klima-allianz.ch\/fr\/#website","url":"https:\/\/www.klima-allianz.ch\/fr\/","name":"Alliance Climatique","description":"","publisher":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klima-allianz.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.klima-allianz.ch\/fr\/#organization","name":"Klima-Allianz","url":"https:\/\/www.klima-allianz.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.klima-allianz.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/KA-Favicon-Kreis-1.png","contentUrl":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/KA-Favicon-Kreis-1.png","width":512,"height":512,"caption":"Klima-Allianz"},"image":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/beitrag\/10122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/beitrag"}],"about":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/types\/beitrag"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/dokumente\/9842"},{"embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/dokumente\/10126"},{"embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/dokumente\/10125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/media\/10073"}],"wp:attachment":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/media?parent=10122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/categories?post=10122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}