{"id":7722,"date":"2022-01-26T08:58:59","date_gmt":"2022-01-26T07:58:59","guid":{"rendered":"https:\/\/www.klima-allianz.ch\/beitrag\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/"},"modified":"2022-04-25T11:28:12","modified_gmt":"2022-04-25T09:28:12","slug":"revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique","status":"publish","type":"beitrag","link":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/","title":{"rendered":"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique"},"content":{"rendered":"<p>La coalition BNS demande \u00e0 cette derni\u00e8re de mettre en \u0153uvre efficacement son mandat et de lutter de mani\u00e8re effective et proactive contre le r\u00e9chauffement climatique et la perte de biodiversit\u00e9. Pour ce faire, elle a besoin de tous les instruments \u00e0 sa disposition, coordonne ses travaux avec la FINMA et informe le Parlement et le public des progr\u00e8s et des autres mesures.<\/p>\n<p><span style=\"text-decoration: underline;\">Plan de transition<\/span> : La BNS et la FINMA publient en 2022 un plan commun avec des mesures concr\u00e8tes en mati\u00e8re de politique mon\u00e9taire et de r\u00e9glementation des march\u00e9s financiers, qui montre comment elles contribuent de mani\u00e8re proactive et efficace \u00e0 la mise en \u0153uvre de la trajectoire de 1,5 degr\u00e9 et des objectifs de biodiversit\u00e9.<\/p>\n<p>1.<span style=\"text-decoration: underline;\">\u00a0R\u00e9serves de devises <\/span>: R\u00e9orientation des\u00a0<span style=\"text-decoration: underline;\">i<\/span>nvestissements de la BNS conform\u00e9ment \u00e0 la trajectoire de 1,5 degr\u00e9 et aux objectifs de biodiversit\u00e9.<br \/>\nCela comprend :<\/p>\n<ul>\n<li>\u00c0 partir de 2022 : Transparence par la publication de toutes les positions\u00a0d&rsquo;investissement du portefeuille et des \u00e9missions de gaz \u00e0 effet de serre et des impacts sur la biodiversit\u00e9 financ\u00e9s.<\/li>\n<li>2022 : Publication de la strat\u00e9gie d&rsquo;investissement qui tient compte de la trajectoire de 1,5 degr\u00e9 et des objectifs de biodiversit\u00e9, et liste de toutes les mesures concr\u00e8tes.<\/li>\n<li>2022 : \u00c9limination des entreprises avec des projets li\u00e9s aux combustibles fossiles et \u00e0 la d\u00e9forestation.<\/li>\n<li>\u00c0 partir de 2023 : Investissement uniquement dans des entreprises ayant un plan de transition significatif et accessible au public (<a href=\"https:\/\/sciencebasedtargets.org\">Science Bases Targets Initiative<\/a>).<\/li>\n<li>Mesurer r\u00e9guli\u00e8rement les progr\u00e8s r\u00e9alis\u00e9s en mati\u00e8re d&rsquo;alignement sur l&rsquo;Accord de Paris et la Convention sur la diversit\u00e9 biologique. En cas de nonalignement, prendre des mesures suppl\u00e9mentaires.<\/li>\n<\/ul>\n<p>2. <span style=\"text-decoration: underline;\">R\u00e9glementation du syst\u00e8me financier suisse<\/span>\u00a0: La BNS collabore avec la FINMA et les d\u00e9cideurs politiques pour prendre toutes les mesures n\u00e9cessaires pour r\u00e9guler l&rsquo;ensemble de la place financi\u00e8re suisse afin de respecter l&rsquo;Accord de Paris et la Convention sur la diversit\u00e9 biologique. Cela comprend:<\/p>\n<ul>\n<li>2022 : un test de r\u00e9sistance macroprudentiel sur le climat et la biodiversit\u00e9 (bas\u00e9 sur le \u00abWorst Case Scenario\u00bb) et sa divulgation publique.<\/li>\n<li>2022 : des exigences de divulgation en mati\u00e8re de climat et de biodiversit\u00e9 pour tous les \u00e9tablissements financiers suisses.<\/li>\n<li>2023 : adapter les exigences de fonds propres en int\u00e9grant les risques li\u00e9s au climat et \u00e0 la biodiversit\u00e9, en publiant la m\u00e9thode utilis\u00e9e. Des exigences de capital \u00abone-for-one\u00bb sont introduites pour les services de cr\u00e9dit et les assurances des nouveaux projets fossiles afin de faire face aux risques climatiques et financiers. Cela signifie simplement que pour chaque franc financ\u00e9, la banque ou l&rsquo;assurance doit mettre de c\u00f4t\u00e9 un franc afin de compenser les pertes futures des industries fossiles.<\/li>\n<li>2023 : Consid\u00e9rer tous les investissements et projets li\u00e9s au p\u00e9trole, au gaz, au charbon et \u00e0 la d\u00e9forestation comme non liquides et non stables.<\/li>\n<li>Mesurer r\u00e9guli\u00e8rement les progr\u00e8s r\u00e9alis\u00e9s en mati\u00e8re d&rsquo;alignement sur l&rsquo;Accord de Paris et la Convention sur la diversit\u00e9 biologique. En cas de nonalignement jusqu\u2019 \u00e0 2025, prendre des mesures suppl\u00e9mentaires.<\/li>\n<\/ul>\n<p>3. <span style=\"text-decoration: underline;\">Dialogue avec les citoyens et redevabilit\u00e9 d\u00e9mocratique<\/span> : la BNS doit chercher \u00e0 s&rsquo;engager davantage avec la soci\u00e9t\u00e9 civile, les citoyens et les experts externes en \u00e9tablissant un processus r\u00e9gulier de consultations publiques et de nouvelles formes de rapports au Parlement.<\/p>\n<p>4. <span style=\"text-decoration: underline;\">Distribution des b\u00e9n\u00e9fices<\/span> : La BNS, la Conf\u00e9d\u00e9ration et les cantons mettent en place un dispositif de distribution des b\u00e9n\u00e9fices qui soutient les objectifs environnementaux et les besoins environnementaux et sociaux urgents de la Suisse.<\/p>\n<p>5. Le <span style=\"text-decoration: underline;\">Conseil f\u00e9d\u00e9ral et le Parlement<\/span> doivent \u00e9laborer le plus rapidement possible les conditions-cadres n\u00e9cessaires. En outre, les gouvernements cantonaux, en tant qu&rsquo;actionnaires principaux de la Banque nationale, doivent assumer leurs responsabilit\u00e9s.<\/p>\n<p>Date: d\u00e9cembre 2021<\/p>\n","protected":false},"featured_media":0,"template":"","categories":[3],"class_list":["post-7722","beitrag","type-beitrag","status-publish","hentry","category-non-classifiee"],"better_featured_image":null,"acf":{"inhaltstyp_mediabox":"image","galerie":null,"video_html":null,"video_vimeo":"","downloads":"","links":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique\" \/>\n<meta property=\"og:description\" content=\"La coalition BNS demande \u00e0 cette derni\u00e8re de mettre en \u0153uvre efficacement son mandat et de lutter de mani\u00e8re effective et proactive contre le r\u00e9chauffement climatique et la perte de biodiversit\u00e9. Pour ce faire, elle a besoin de tous les instruments \u00e0 sa disposition, coordonne ses travaux avec la FINMA et informe le Parlement et &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/\" \/>\n<meta property=\"og:site_name\" content=\"Alliance Climatique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-25T09:28:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\\\/\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\\\/\",\"name\":\"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#website\"},\"datePublished\":\"2022-01-26T07:58:59+00:00\",\"dateModified\":\"2022-04-25T09:28:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beitr\u00e4ge\",\"item\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/article\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\",\"name\":\"Alliance Climatique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#organization\",\"name\":\"Klima-Allianz\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/KA-Favicon-Kreis-1.png\",\"contentUrl\":\"https:\\\/\\\/www.klima-allianz.ch\\\/wp-content\\\/uploads\\\/KA-Favicon-Kreis-1.png\",\"width\":512,\"height\":512,\"caption\":\"Klima-Allianz\"},\"image\":{\"@id\":\"https:\\\/\\\/www.klima-allianz.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/","og_locale":"fr_FR","og_type":"article","og_title":"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique","og_description":"La coalition BNS demande \u00e0 cette derni\u00e8re de mettre en \u0153uvre efficacement son mandat et de lutter de mani\u00e8re effective et proactive contre le r\u00e9chauffement climatique et la perte de biodiversit\u00e9. Pour ce faire, elle a besoin de tous les instruments \u00e0 sa disposition, coordonne ses travaux avec la FINMA et informe le Parlement et &hellip; Continued","og_url":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/","og_site_name":"Alliance Climatique","article_modified_time":"2022-04-25T09:28:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/","url":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/","name":"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique &#8226; Alliance Climatique","isPartOf":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#website"},"datePublished":"2022-01-26T07:58:59+00:00","dateModified":"2022-04-25T09:28:12+00:00","breadcrumb":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.klima-allianz.ch\/fr\/article\/revendications-du-groupe-de-travail-bns-de-lalliance-climatique-aupres-de-la-bns-la-finma-et-la-politique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.klima-allianz.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Beitr\u00e4ge","item":"https:\/\/www.klima-allianz.ch\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"Revendications de la coalition BNS aupr\u00e8s de la BNS, la FINMA et la politique"}]},{"@type":"WebSite","@id":"https:\/\/www.klima-allianz.ch\/fr\/#website","url":"https:\/\/www.klima-allianz.ch\/fr\/","name":"Alliance Climatique","description":"","publisher":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.klima-allianz.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.klima-allianz.ch\/fr\/#organization","name":"Klima-Allianz","url":"https:\/\/www.klima-allianz.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.klima-allianz.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/KA-Favicon-Kreis-1.png","contentUrl":"https:\/\/www.klima-allianz.ch\/wp-content\/uploads\/KA-Favicon-Kreis-1.png","width":512,"height":512,"caption":"Klima-Allianz"},"image":{"@id":"https:\/\/www.klima-allianz.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/beitrag\/7722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/beitrag"}],"about":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/types\/beitrag"}],"wp:attachment":[{"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/media?parent=7722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.klima-allianz.ch\/fr\/wp-json\/wp\/v2\/categories?post=7722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}